{"id":5003,"date":"2023-03-10T11:32:56","date_gmt":"2023-03-10T10:32:56","guid":{"rendered":"https:\/\/african-futures.koeln\/events\/decolonizing-approaches-on-black-health-black-voices-une-table-ronde-entre-medecins-noirs\/"},"modified":"2023-06-12T10:45:31","modified_gmt":"2023-06-12T08:45:31","slug":"decolonizing-approaches-on-black-health-black-voices-une-table-ronde-entre-medecins-noirs","status":"publish","type":"mec-events","link":"https:\/\/african-futures.koeln\/fr\/events\/decolonizing-approaches-on-black-health-black-voices-une-table-ronde-entre-medecins-noirs\/","title":{"rendered":"Decolonizing Approaches on Black Health : Black Voices &#8211; Une table ronde entre m\u00e9decins noirs*."},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\" style=\"font-style:normal;font-weight:700\"><strong>La sant\u00e9 est un droit humain<\/strong><\/h2>\n\n<p>Cela signifie que toute personne, ind\u00e9pendamment de son origine, de son sexe, de son statut social, de sa religion, de son orientation sexuelle, etc. devrait avoir un acc\u00e8s \u00e9gal \u00e0 des soins m\u00e9dicaux de qualit\u00e9 \u00e9gale. Ce droit doit \u00eatre mis en \u0153uvre conform\u00e9ment au Pacte social des Nations unies. La r\u00e9alit\u00e9 parle toutefois un autre langage. De nombreuses personnes sont certainement conscientes des diff\u00e9rences en mati\u00e8re de soins m\u00e9dicaux compte tenu des positions politiques et socio-\u00e9conomiques divergentes des pays du Sud et du Nord de la plan\u00e8te, qui doivent \u00eatre replac\u00e9es dans le contexte du syst\u00e8me mondial. Au plus fort de la pand\u00e9mie, la discrimination et l&rsquo;exclusion, notamment en raison de l&rsquo;origine ethnique, \u00e9taient encore plus visibles qu&rsquo;elles ne l&rsquo;\u00e9taient d\u00e9j\u00e0 (rapport annuel 2020 de l&rsquo;Antidiskriminierungsstelle des Bundes ADS). C&rsquo;est pourquoi il est important de percevoir et de nommer les d\u00e9savantages subis par les Noirs en mati\u00e8re de soins de sant\u00e9 et, dans une prochaine \u00e9tape, de les mesurer et de les analyser &#8211; comme cela a \u00e9t\u00e9 fait pour la premi\u00e8re fois dans l&rsquo;Afrozensus 2020. Dans ce contexte, il est important de se pencher d&rsquo;abord sur l&rsquo;histoire de la m\u00e9decine, sur les continuit\u00e9s coloniales dans les structures ainsi que sur la terminologie clinique afin de sensibiliser toutes les personnes impliqu\u00e9es dans les soins de sant\u00e9.<\/p>\n\n<h2 class=\"wp-block-heading has-medium-font-size\" style=\"font-style:normal;font-weight:700;text-transform:uppercase\">Organisateur<\/h2>\n\n<p><a href=\"https:\/\/www.facebook.com\/SCDGGermany\" target=\"_blank\" rel=\"noopener\">Tournesol Community Development Group e.V. (Groupe de d\u00e9veloppement communautaire Tournesol)<\/a><\/p>\n\n<p>L&rsquo;\u00e9v\u00e9nement est soutenu par la <a href=\"https:\/\/www.stadt-koeln.de\/artikel\/72503\/index.html\" target=\"_blank\" rel=\"noopener\">ville de Cologne<\/a> et la <a href=\"https:\/\/www.vhs-koeln.de\/\" target=\"_blank\" rel=\"noopener\">Volkshochschule K\u00f6ln<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela signifie que toute personne, ind\u00e9pendamment de son origine, de son sexe, de son statut social, de sa religion, de son orientation sexuelle, etc. doit avoir un acc\u00e8s \u00e9gal \u00e0 des soins m\u00e9dicaux de qualit\u00e9 \u00e9gale.<\/p>\n","protected":false},"author":1,"featured_media":4861,"comment_status":"closed","ping_status":"closed","template":"","mec_category":[306],"programmbereich":[],"mec_tag":[641],"class_list":["post-5003","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","mec_category-societe-politique","mec_tag-ensemble-sur-le-chemin"],"acf":[],"_links":{"self":[{"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/mec-events\/5003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/comments?post=5003"}],"version-history":[{"count":2,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/mec-events\/5003\/revisions"}],"predecessor-version":[{"id":7473,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/mec-events\/5003\/revisions\/7473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/media\/4861"}],"wp:attachment":[{"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/media?parent=5003"}],"wp:term":[{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/mec_category?post=5003"},{"taxonomy":"programmbereich","embeddable":true,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/programmbereich?post=5003"},{"taxonomy":"mec_tag","embeddable":true,"href":"https:\/\/african-futures.koeln\/fr\/wp-json\/wp\/v2\/mec_tag?post=5003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}